{"id":18536,"count":1,"description":"","link":"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/","name":"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28","slug":"%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theleonews.com\/en\/Tag\/\u0c1c\u0c3e\u0c24\u0c15-\u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theleonews.com\/en\/Tag\/\u0c1c\u0c3e\u0c24\u0c15-\u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28\/\" \/>\n<meta property=\"og:site_name\" content=\"The Leo News | English News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/\",\"url\":\"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/\",\"name\":\"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News\",\"isPartOf\":{\"@id\":\"https:\/\/www.theleonews.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.theleonews.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.theleonews.com\/en\/#website\",\"url\":\"https:\/\/www.theleonews.com\/en\/\",\"name\":\"The Leo News | English News\",\"description\":\"Andhra News | Telangana News | Tollywood\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.theleonews.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theleonews.com\/en\/Tag\/\u0c1c\u0c3e\u0c24\u0c15-\u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28\/","og_locale":"en_US","og_type":"article","og_title":"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News","og_url":"https:\/\/www.theleonews.com\/en\/Tag\/\u0c1c\u0c3e\u0c24\u0c15-\u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28\/","og_site_name":"The Leo News | English News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/","url":"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/","name":"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28 Archives - The Leo News | English News","isPartOf":{"@id":"https:\/\/www.theleonews.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.theleonews.com\/en\/Tag\/%e0%b0%9c%e0%b0%be%e0%b0%a4%e0%b0%95-%e0%b0%aa%e0%b0%b0%e0%b0%bf%e0%b0%b6%e0%b1%80%e0%b0%b2%e0%b0%a8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theleonews.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u0c1c\u0c3e\u0c24\u0c15 \u0c2a\u0c30\u0c3f\u0c36\u0c40\u0c32\u0c28"}]},{"@type":"WebSite","@id":"https:\/\/www.theleonews.com\/en\/#website","url":"https:\/\/www.theleonews.com\/en\/","name":"The Leo News | English News","description":"Andhra News | Telangana News | Tollywood","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theleonews.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.theleonews.com\/en\/wp-json\/wp\/v2\/tags\/18536"}],"collection":[{"href":"https:\/\/www.theleonews.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.theleonews.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.theleonews.com\/en\/wp-json\/wp\/v2\/posts?tags=18536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}